{"id":13052,"date":"2023-02-02T16:18:26","date_gmt":"2023-02-02T21:18:26","guid":{"rendered":"https:\/\/sites.udmercy.edu\/campusconnection\/wp-content\/uploads\/sites\/106\/2023\/02\/230201-VHT-145.jpg"},"modified":"2023-02-02T16:24:28","modified_gmt":"2023-02-02T21:24:28","slug":"230201-vht-145","status":"inherit","type":"attachment","link":"https:\/\/sites.udmercy.edu\/campusconnection\/2023\/02\/02\/photos-fashion-show-fun\/230201-vht-145\/","title":{"rendered":"230201-Fashion-Show-5"},"author":224,"comment_status":"closed","ping_status":"closed","template":"","meta":{"jetpack_post_was_ever_published":false},"smush":{"stats":{"percent":18.460869455877546130295741022564470767974853515625,"bytes":880901,"size_before":4771720,"size_after":3890819,"time":4.1899999999999995026200849679298698902130126953125,"api_version":"1.0","lossy":1,"keep_exif":0},"sizes":{"thumbnail":{"percent":82.2000000000000028421709430404007434844970703125,"bytes":29956,"size_before":36445,"size_after":6489,"time":0.01000000000000000020816681711721685132943093776702880859375},"medium":{"percent":68.2399999999999948840923025272786617279052734375,"bytes":31905,"size_before":46752,"size_after":14847,"time":0.01000000000000000020816681711721685132943093776702880859375},"fluida-lpbox-1":{"percent":59.090000000000003410605131648480892181396484375,"bytes":33993,"size_before":57525,"size_after":23532,"time":0.0200000000000000004163336342344337026588618755340576171875},"fluida-lpbox-2":{"percent":49.68999999999999772626324556767940521240234375,"bytes":36940,"size_before":74346,"size_after":37406,"time":0.040000000000000000832667268468867405317723751068115234375},"fluida-featured-third":{"percent":43.52000000000000312638803734444081783294677734375,"bytes":39322,"size_before":90349,"size_after":51027,"time":0.040000000000000000832667268468867405317723751068115234375},"fluida-featured-half":{"percent":36.78999999999999914734871708787977695465087890625,"bytes":44069,"size_before":119800,"size_after":75731,"time":0.05000000000000000277555756156289135105907917022705078125},"fluida-featured":{"percent":31.800000000000000710542735760100185871124267578125,"bytes":49211,"size_before":154739,"size_after":105528,"time":0.08000000000000000166533453693773481063544750213623046875},"fluida-header":{"percent":32.78999999999999914734871708787977695465087890625,"bytes":45595,"size_before":139046,"size_after":93451,"time":0.070000000000000006661338147750939242541790008544921875},"fluida-featured-lp":{"percent":31.25,"bytes":49720,"size_before":159114,"size_after":109394,"time":0.08000000000000000166533453693773481063544750213623046875},"large":{"percent":30.339999999999999857891452847979962825775146484375,"bytes":52121,"size_before":171818,"size_after":119697,"time":0.11999999999999999555910790149937383830547332763671875},"1536x1536":{"percent":22.3299999999999982946974341757595539093017578125,"bytes":71533,"size_before":320326,"size_after":248793,"time":0.2800000000000000266453525910037569701671600341796875},"2048x2048":{"percent":18.89999999999999857891452847979962825775146484375,"bytes":97519,"size_before":515969,"size_after":418450,"time":0.330000000000000015543122344752191565930843353271484375},"medium_large":{"percent":37.5499999999999971578290569595992565155029296875,"bytes":43436,"size_before":115677,"size_after":72241,"time":0.299999999999999988897769753748434595763683319091796875},"wp_scaled":{"percent":17.07000000000000028421709430404007434844970703125,"bytes":128552,"size_before":753148,"size_after":624596,"time":0.63000000000000000444089209850062616169452667236328125},"post-thumbnail":{"percent":37.409999999999996589394868351519107818603515625,"bytes":43422,"size_before":116060,"size_after":72638,"time":0.08000000000000000166533453693773481063544750213623046875},"full":{"percent":4.4000000000000003552713678800500929355621337890625,"bytes":83607,"size_before":1900606,"size_after":1816999,"time":2.04999999999999982236431605997495353221893310546875}}},"jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/abwnTV-3ow","description":{"rendered":"<p class=\"attachment\"><a href='https:\/\/i0.wp.com\/sites.udmercy.edu\/campusconnection\/wp-content\/uploads\/sites\/106\/2023\/02\/230201-VHT-145-scaled.jpg?ssl=1'><img width=\"300\" height=\"214\" src=\"https:\/\/i0.wp.com\/sites.udmercy.edu\/campusconnection\/wp-content\/uploads\/sites\/106\/2023\/02\/230201-VHT-145-scaled.jpg?fit=300%2C214&amp;ssl=1\" class=\"attachment-medium size-medium\" alt=\"Eleven people pose for a photo indoors, most of them standing and one kneeling. Two people wear Pace Yourself t-shirts that are visible.\" decoding=\"async\" srcset=\"https:\/\/i0.wp.com\/sites.udmercy.edu\/campusconnection\/wp-content\/uploads\/sites\/106\/2023\/02\/230201-VHT-145-scaled.jpg?w=2560&amp;ssl=1 2560w, https:\/\/i0.wp.com\/sites.udmercy.edu\/campusconnection\/wp-content\/uploads\/sites\/106\/2023\/02\/230201-VHT-145-scaled.jpg?resize=300%2C214&amp;ssl=1 300w, https:\/\/i0.wp.com\/sites.udmercy.edu\/campusconnection\/wp-content\/uploads\/sites\/106\/2023\/02\/230201-VHT-145-scaled.jpg?resize=1024%2C731&amp;ssl=1 1024w, https:\/\/i0.wp.com\/sites.udmercy.edu\/campusconnection\/wp-content\/uploads\/sites\/106\/2023\/02\/230201-VHT-145-scaled.jpg?resize=768%2C549&amp;ssl=1 768w, https:\/\/i0.wp.com\/sites.udmercy.edu\/campusconnection\/wp-content\/uploads\/sites\/106\/2023\/02\/230201-VHT-145-scaled.jpg?resize=1536%2C1097&amp;ssl=1 1536w, https:\/\/i0.wp.com\/sites.udmercy.edu\/campusconnection\/wp-content\/uploads\/sites\/106\/2023\/02\/230201-VHT-145-scaled.jpg?resize=2048%2C1463&amp;ssl=1 2048w, https:\/\/i0.wp.com\/sites.udmercy.edu\/campusconnection\/wp-content\/uploads\/sites\/106\/2023\/02\/230201-VHT-145-scaled.jpg?resize=770%2C550&amp;ssl=1 770w, https:\/\/i0.wp.com\/sites.udmercy.edu\/campusconnection\/wp-content\/uploads\/sites\/106\/2023\/02\/230201-VHT-145-scaled.jpg?w=1986&amp;ssl=1 1986w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a><\/p>\n"},"caption":{"rendered":""},"alt_text":"Eleven people pose for a photo indoors, most of them standing and one kneeling. Two people wear Pace Yourself t-shirts that are visible.","media_type":"image","mime_type":"image\/jpeg","media_details":{"width":2560,"height":1828,"file":"2023\/02\/230201-VHT-145-scaled.jpg","filesize":"753148","sizes":{"medium":{"file":"230201-VHT-145-300x214.jpg","width":300,"height":214,"filesize":"46752","mime_type":"image\/jpeg","source_url":"https:\/\/i0.wp.com\/sites.udmercy.edu\/campusconnection\/wp-content\/uploads\/sites\/106\/2023\/02\/230201-VHT-145-scaled.jpg?fit=300%2C214&ssl=1"},"large":{"file":"230201-VHT-145-1024x731.jpg","width":1024,"height":731,"filesize":"171818","mime_type":"image\/jpeg","source_url":"https:\/\/i0.wp.com\/sites.udmercy.edu\/campusconnection\/wp-content\/uploads\/sites\/106\/2023\/02\/230201-VHT-145-scaled.jpg?fit=993%2C709&ssl=1"},"thumbnail":{"file":"230201-VHT-145-150x150.jpg","width":150,"height":150,"filesize":"36445","mime_type":"image\/jpeg","source_url":"https:\/\/i0.wp.com\/sites.udmercy.edu\/campusconnection\/wp-content\/uploads\/sites\/106\/2023\/02\/230201-VHT-145-scaled.jpg?resize=150%2C150&ssl=1"},"medium_large":{"file":"230201-VHT-145-768x549.jpg","width":768,"height":549,"filesize":"115677","mime_type":"image\/jpeg","source_url":"https:\/\/i0.wp.com\/sites.udmercy.edu\/campusconnection\/wp-content\/uploads\/sites\/106\/2023\/02\/230201-VHT-145-scaled.jpg?fit=768%2C549&ssl=1"},"1536x1536":{"file":"230201-VHT-145-1536x1097.jpg","width":1536,"height":1097,"filesize":"320326","mime_type":"image\/jpeg","source_url":"https:\/\/i0.wp.com\/sites.udmercy.edu\/campusconnection\/wp-content\/uploads\/sites\/106\/2023\/02\/230201-VHT-145-scaled.jpg?fit=1536%2C1097&ssl=1"},"2048x2048":{"file":"230201-VHT-145-2048x1463.jpg","width":2048,"height":1463,"filesize":"515969","mime_type":"image\/jpeg","source_url":"https:\/\/i0.wp.com\/sites.udmercy.edu\/campusconnection\/wp-content\/uploads\/sites\/106\/2023\/02\/230201-VHT-145-scaled.jpg?fit=2048%2C1463&ssl=1"},"post-thumbnail":{"file":"230201-VHT-145-770x550.jpg","width":770,"height":550,"filesize":"116060","mime_type":"image\/jpeg","source_url":"https:\/\/i0.wp.com\/sites.udmercy.edu\/campusconnection\/wp-content\/uploads\/sites\/106\/2023\/02\/230201-VHT-145-scaled.jpg?fit=770%2C550&ssl=1"},"fluida-featured":{"file":"230201-VHT-145-1204x550.jpg","width":1204,"height":550,"filesize":"154739","mime_type":"image\/jpeg","source_url":"https:\/\/i0.wp.com\/sites.udmercy.edu\/campusconnection\/wp-content\/uploads\/sites\/106\/2023\/02\/230201-VHT-145-scaled.jpg?resize=1204%2C550&ssl=1"},"fluida-featured-lp":{"file":"230201-VHT-145-1280x550.jpg","width":1280,"height":550,"filesize":"159114","mime_type":"image\/jpeg","source_url":"https:\/\/i0.wp.com\/sites.udmercy.edu\/campusconnection\/wp-content\/uploads\/sites\/106\/2023\/02\/230201-VHT-145-scaled.jpg?resize=1280%2C550&ssl=1"},"fluida-featured-half":{"file":"230201-VHT-145-800x550.jpg","width":800,"height":550,"filesize":"119800","mime_type":"image\/jpeg","source_url":"https:\/\/i0.wp.com\/sites.udmercy.edu\/campusconnection\/wp-content\/uploads\/sites\/106\/2023\/02\/230201-VHT-145-scaled.jpg?resize=800%2C550&ssl=1"},"fluida-featured-third":{"file":"230201-VHT-145-512x550.jpg","width":512,"height":550,"filesize":"90349","mime_type":"image\/jpeg","source_url":"https:\/\/i0.wp.com\/sites.udmercy.edu\/campusconnection\/wp-content\/uploads\/sites\/106\/2023\/02\/230201-VHT-145-scaled.jpg?resize=512%2C550&ssl=1"},"fluida-header":{"file":"230201-VHT-145-1920x375.jpg","width":1920,"height":375,"filesize":"139046","mime_type":"image\/jpeg","source_url":"https:\/\/i0.wp.com\/sites.udmercy.edu\/campusconnection\/wp-content\/uploads\/sites\/106\/2023\/02\/230201-VHT-145-scaled.jpg?resize=1920%2C375&ssl=1"},"fluida-lpbox-1":{"file":"230201-VHT-145-426x250.jpg","width":426,"height":250,"filesize":"57525","mime_type":"image\/jpeg","source_url":"https:\/\/i0.wp.com\/sites.udmercy.edu\/campusconnection\/wp-content\/uploads\/sites\/106\/2023\/02\/230201-VHT-145-scaled.jpg?resize=426%2C250&ssl=1"},"fluida-lpbox-2":{"file":"230201-VHT-145-480x400.jpg","width":480,"height":400,"filesize":"74346","mime_type":"image\/jpeg","source_url":"https:\/\/i0.wp.com\/sites.udmercy.edu\/campusconnection\/wp-content\/uploads\/sites\/106\/2023\/02\/230201-VHT-145-scaled.jpg?resize=480%2C400&ssl=1"},"full":{"file":"230201-VHT-145-scaled.jpg?fit=2560%2C1828&ssl=1","width":2560,"height":1828,"mime_type":"image\/jpeg","source_url":"https:\/\/i0.wp.com\/sites.udmercy.edu\/campusconnection\/wp-content\/uploads\/sites\/106\/2023\/02\/230201-VHT-145-scaled.jpg?fit=2560%2C1828&ssl=1"}},"image_meta":{"aperture":"4","credit":"","camera":"ILCE-7M3","caption":"","created_timestamp":"1675303590","copyright":"","focal_length":"32","iso":"500","shutter_speed":"0.008","title":"","orientation":"0"},"original_image":"230201-VHT-145.jpg"},"post":13047,"source_url":"https:\/\/sites.udmercy.edu\/campusconnection\/wp-content\/uploads\/sites\/106\/2023\/02\/230201-VHT-145-scaled.jpg","_links":{"self":[{"href":"https:\/\/sites.udmercy.edu\/campusconnection\/wp-json\/wp\/v2\/media\/13052"}],"collection":[{"href":"https:\/\/sites.udmercy.edu\/campusconnection\/wp-json\/wp\/v2\/media"}],"about":[{"href":"https:\/\/sites.udmercy.edu\/campusconnection\/wp-json\/wp\/v2\/types\/attachment"}],"author":[{"embeddable":true,"href":"https:\/\/sites.udmercy.edu\/campusconnection\/wp-json\/wp\/v2\/users\/224"}],"replies":[{"embeddable":true,"href":"https:\/\/sites.udmercy.edu\/campusconnection\/wp-json\/wp\/v2\/comments?post=13052"}]}}