{"id":2355,"count":115,"description":"","link":"https:\/\/sites.udmercy.edu\/campusconnection\/tag\/college-of-health-professions\/","name":"College of Health Professions","slug":"college-of-health-professions","taxonomy":"post_tag","meta":[],"_links":{"self":[{"href":"https:\/\/sites.udmercy.edu\/campusconnection\/wp-json\/wp\/v2\/tags\/2355"}],"collection":[{"href":"https:\/\/sites.udmercy.edu\/campusconnection\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/sites.udmercy.edu\/campusconnection\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/sites.udmercy.edu\/campusconnection\/wp-json\/wp\/v2\/posts?tags=2355"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}